{"id":178,"count":2,"description":"Los paneles antica\u00edda de malla electrosoldada de la serie SI.S.MA est\u00e1n dise\u00f1ados para evitar la ca\u00edda accidental de materiales en estanter\u00edas de almacenes y zonas log\u00edsticas. Su exclusivo dise\u00f1o de los sistemas de conexi\u00f3n permite la uni\u00f3n a cualquier perfil o estanter\u00eda, sin limitaci\u00f3n de tama\u00f1o, altura o anchura para la mayor\u00eda de los inter ejes del mercado.\r\n\r\nPuede dise\u00f1ar y comprar de forma independiente los paneles, los estantes y las rejillas, utilizando nuestro software de configuraci\u00f3n.","link":"https:\/\/www.accessafe.eu\/es\/categoria-de-producto\/paneles-y-estantes-anticaida\/paneles-anticaida-serie-si-s-ma\/","name":"Paneles antica\u00edda Serie SI.S.MA","slug":"paneles-anticaida-serie-si-s-ma","taxonomy":"product_cat","parent":177,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Dispositivi di protezione anticaduta Serie SI.S.MA | Access<\/title>\n<meta name=\"description\" content=\"Le protezioni in rete elettrosaldata per anticaduta Serie SI.S.MA sono realizzate per prevenire la caduta accidentale di materiali su scaffalature.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.accessafe.eu\/es\/categoria-de-producto\/paneles-y-estantes-anticaida\/paneles-anticaida-serie-si-s-ma\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paneles antica\u00edda Serie SI.S.MA Archivi\" \/>\n<meta property=\"og:description\" content=\"Le protezioni in rete elettrosaldata per anticaduta Serie SI.S.MA sono realizzate per prevenire la caduta accidentale di materiali su scaffalature.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.accessafe.eu\/es\/categoria-de-producto\/paneles-y-estantes-anticaida\/paneles-anticaida-serie-si-s-ma\/\" \/>\n<meta property=\"og:site_name\" content=\"Accessafe\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.accessafe.eu\/wp-content\/uploads\/2025\/05\/accessafe-protezioni-perimentrali.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.accessafe.eu\\\/es\\\/categoria-de-producto\\\/paneles-y-estantes-anticaida\\\/paneles-anticaida-serie-si-s-ma\\\/\",\"url\":\"https:\\\/\\\/www.accessafe.eu\\\/es\\\/categoria-de-producto\\\/paneles-y-estantes-anticaida\\\/paneles-anticaida-serie-si-s-ma\\\/\",\"name\":\"Dispositivi di protezione anticaduta Serie SI.S.MA | Access\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.accessafe.eu\\\/es\\\/#website\"},\"description\":\"Le protezioni in rete elettrosaldata per anticaduta Serie SI.S.MA sono realizzate per prevenire la caduta accidentale di materiali su scaffalature.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.accessafe.eu\\\/es\\\/categoria-de-producto\\\/paneles-y-estantes-anticaida\\\/paneles-anticaida-serie-si-s-ma\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.accessafe.eu\\\/es\\\/categoria-de-producto\\\/paneles-y-estantes-anticaida\\\/paneles-anticaida-serie-si-s-ma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.accessafe.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protecci\u00f3n contra ca\u00eddas y estanter\u00edas para almacenes verticales\",\"item\":\"https:\\\/\\\/www.accessafe.eu\\\/es\\\/categoria-de-producto\\\/paneles-y-estantes-anticaida\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Paneles antica\u00edda Serie SI.S.MA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.accessafe.eu\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.accessafe.eu\\\/es\\\/\",\"name\":\"Accessafe\",\"description\":\"Accessafe partner globale per la sicurezza industriale\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.accessafe.eu\\\/es\\\/#organization\"},\"alternateName\":\"Accessafe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.accessafe.eu\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.accessafe.eu\\\/es\\\/#organization\",\"name\":\"Accessafe\",\"alternateName\":\"Accessafe\",\"url\":\"https:\\\/\\\/www.accessafe.eu\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.accessafe.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.accessafe.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/accessafe-logotipo.png\",\"contentUrl\":\"https:\\\/\\\/www.accessafe.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/accessafe-logotipo.png\",\"width\":400,\"height\":66,\"caption\":\"Accessafe\"},\"image\":{\"@id\":\"https:\\\/\\\/www.accessafe.eu\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"description\":\"Accessafe \u00e8 il partner globale per la sicurezza industriale: con sistemi di protezione perimetrale, consulenze e soluzioni per la marcatura CE dei macchinari, trasformiamo gli ambienti produttivi in spazi sicuri, efficienti e rispettosi dell\u2019ambiente.\",\"email\":\"info@accessafe.eu\",\"telephone\":\"+390399515951\",\"legalName\":\"Access Srl\",\"vatID\":\"05718410961\",\"taxID\":\"05718410961\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dispositivi di protezione anticaduta Serie SI.S.MA | Access","description":"Le protezioni in rete elettrosaldata per anticaduta Serie SI.S.MA sono realizzate per prevenire la caduta accidentale di materiali su scaffalature.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.accessafe.eu\/es\/categoria-de-producto\/paneles-y-estantes-anticaida\/paneles-anticaida-serie-si-s-ma\/","og_locale":"es_ES","og_type":"article","og_title":"Paneles antica\u00edda Serie SI.S.MA Archivi","og_description":"Le protezioni in rete elettrosaldata per anticaduta Serie SI.S.MA sono realizzate per prevenire la caduta accidentale di materiali su scaffalature.","og_url":"https:\/\/www.accessafe.eu\/es\/categoria-de-producto\/paneles-y-estantes-anticaida\/paneles-anticaida-serie-si-s-ma\/","og_site_name":"Accessafe","og_image":[{"width":1920,"height":800,"url":"https:\/\/www.accessafe.eu\/wp-content\/uploads\/2025\/05\/accessafe-protezioni-perimentrali.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.accessafe.eu\/es\/categoria-de-producto\/paneles-y-estantes-anticaida\/paneles-anticaida-serie-si-s-ma\/","url":"https:\/\/www.accessafe.eu\/es\/categoria-de-producto\/paneles-y-estantes-anticaida\/paneles-anticaida-serie-si-s-ma\/","name":"Dispositivi di protezione anticaduta Serie SI.S.MA | Access","isPartOf":{"@id":"https:\/\/www.accessafe.eu\/es\/#website"},"description":"Le protezioni in rete elettrosaldata per anticaduta Serie SI.S.MA sono realizzate per prevenire la caduta accidentale di materiali su scaffalature.","breadcrumb":{"@id":"https:\/\/www.accessafe.eu\/es\/categoria-de-producto\/paneles-y-estantes-anticaida\/paneles-anticaida-serie-si-s-ma\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.accessafe.eu\/es\/categoria-de-producto\/paneles-y-estantes-anticaida\/paneles-anticaida-serie-si-s-ma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.accessafe.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Protecci\u00f3n contra ca\u00eddas y estanter\u00edas para almacenes verticales","item":"https:\/\/www.accessafe.eu\/es\/categoria-de-producto\/paneles-y-estantes-anticaida\/"},{"@type":"ListItem","position":3,"name":"Paneles antica\u00edda Serie SI.S.MA"}]},{"@type":"WebSite","@id":"https:\/\/www.accessafe.eu\/es\/#website","url":"https:\/\/www.accessafe.eu\/es\/","name":"Accessafe","description":"Accessafe partner globale per la sicurezza industriale","publisher":{"@id":"https:\/\/www.accessafe.eu\/es\/#organization"},"alternateName":"Accessafe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.accessafe.eu\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.accessafe.eu\/es\/#organization","name":"Accessafe","alternateName":"Accessafe","url":"https:\/\/www.accessafe.eu\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.accessafe.eu\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.accessafe.eu\/wp-content\/uploads\/2026\/03\/accessafe-logotipo.png","contentUrl":"https:\/\/www.accessafe.eu\/wp-content\/uploads\/2026\/03\/accessafe-logotipo.png","width":400,"height":66,"caption":"Accessafe"},"image":{"@id":"https:\/\/www.accessafe.eu\/es\/#\/schema\/logo\/image\/"},"description":"Accessafe \u00e8 il partner globale per la sicurezza industriale: con sistemi di protezione perimetrale, consulenze e soluzioni per la marcatura CE dei macchinari, trasformiamo gli ambienti produttivi in spazi sicuri, efficienti e rispettosi dell\u2019ambiente.","email":"info@accessafe.eu","telephone":"+390399515951","legalName":"Access Srl","vatID":"05718410961","taxID":"05718410961"}]}},"_links":{"self":[{"href":"https:\/\/www.accessafe.eu\/es\/wp-json\/wp\/v2\/product_cat\/178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.accessafe.eu\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.accessafe.eu\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.accessafe.eu\/es\/wp-json\/wp\/v2\/product_cat\/177"}],"wp:post_type":[{"href":"https:\/\/www.accessafe.eu\/es\/wp-json\/wp\/v2\/product?product_cat=178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}